{"id":141472,"date":"2025-09-03T17:46:34","date_gmt":"2025-09-03T12:16:34","guid":{"rendered":"https:\/\/indusvalleytimes.com\/news\/?p=141472"},"modified":"2025-09-03T17:46:35","modified_gmt":"2025-09-03T12:16:35","slug":"%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95","status":"publish","type":"post","link":"http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/","title":{"rendered":"\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15 \u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15 \u0b2c\u0b5f\u0b3e\u0b28 : \u0b15\u0b39\u0b3f\u0b32\u0b47- \u0b2e\u0b4b \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15 \u0b39\u0b3f\u0b01 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20, \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01"},"content":{"rendered":"\n<p class=\"caps\">\u0b2d\u0b41\u0b2c\u0b28\u0b47\u0b36\u0b4d\u0b71\u0b30, \u0b69\/\u0b6f : \u0b2c\u0b3f\u0b1c\u0b41 \u0b1c\u0b28\u0b24\u0b3e \u0b26\u0b33\u0b30 \u0b2c\u0b30\u0b3f\u0b37\u0b4d\u0b20 \u0b28\u0b47\u0b24\u0b3e \u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02 \u0b2a\u0b41\u0b23\u0b3f \u0b25\u0b30\u0b47 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b06\u0b21\u0b3c\u0b41\u0b15 \u0b22\u0b33\u0b41\u0b25\u0b3f\u0b2c\u0b3e \u0b2a\u0b4d\u0b30\u0b24\u0b40\u0b5f\u0b2e\u0b3e\u0b28 \u0b39\u0b47\u0b09\u0b1b\u0b3f \u0964 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b18\u0b30 \u0b2c\u0b3e\u0b39\u0b41\u0b21\u0b3c\u0b3e \u0b15\u0b30\u0b3f\u0b2c\u0b3e\u0b15\u0b41 \u0b38\u0b19\u0b4d\u0b15\u0b47\u0b24 \u0b26\u0b47\u0b32\u0b47\u0b23\u0b3f \u0964 \u0b24\u0b3e\u0b19\u0b4d\u0b15 \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15\u0b47 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20 \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01 \u0b2c\u0b4b\u0b32\u0b3f \u0b2a\u0b4d\u0b30\u0b24\u0b3f\u0b15\u0b4d\u0b30\u0b3f\u0b5f\u0b3e \u0b26\u0b47\u0b07\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0964<br>\u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b1b\u0b3e\u0b21\u0b3c\u0b3f \u0b2c\u0b3f\u0b1c\u0b47\u0b21\u0b3c\u0b3f\u0b30\u0b47 \u0b2e\u0b3f\u0b36\u0b3f\u0b25\u0b3f\u0b2c\u0b3e \u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30\u0b19\u0b4d\u0b15 \u0b2e\u0b28 \u0b27\u0b3f\u0b30\u0b47 \u0b27\u0b3f\u0b30\u0b47 \u0b2a\u0b30\u0b3f\u0b2c\u0b30\u0b4d\u0b24\u0b4d\u0b24\u0b28 \u0b39\u0b47\u0b2c\u0b3e \u0b26\u0b47\u0b16\u0b3e\u0b2f\u0b3e\u0b09\u0b1b\u0b3f \u0964 \u0b38\u0b47 \u0b15\u0b39\u0b3f\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0b2f\u0b47 \u0b24\u0b3e\u0b19\u0b4d\u0b15 \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15\u0b47 \u0b39\u0b3f\u0b01 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20 \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01 \u0964 \u0b2e\u0b4b\u0b30 \u0b2d\u0b2c\u0b3f\u0b37\u0b4d\u0b5f\u0b24 \u0b15\u0b23 \u0b39\u0b47\u0b2c \u0b24\u0b3e\u0b39\u0b3e \u0b32\u0b4b\u0b15\u0b47 \u0b28\u0b3f\u0b37\u0b4d\u0b2a\u0b24\u0b4d\u0b24\u0b3f \u0b28\u0b47\u0b2c\u0b47 \u0964 \u0b2f\u0b47\u0b09\u0b01 \u0b1a\u0b3f\u0b39\u0b4d\u0b28\u0b30\u0b47 \u0b1b\u0b3f\u0b21\u0b3c\u0b3e \u0b39\u0b47\u0b32\u0b47 \u0b32\u0b4b\u0b15\u0b47 \u0b2d\u0b4b\u0b1f\u0b47 \u0b26\u0b47\u0b2c\u0b47 \u0b15\u0b39\u0b41\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0964<br>\u0b0f\u0b39\u0b3e\u0b30\u0b3f \u0b2e\u0b27\u0b4d\u0b5f\u0b30\u0b47 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38\u0b15\u0b41 \u0b2e\u0b27\u0b4d\u0b5f \u0b2a\u0b4d\u0b30\u0b36\u0b02\u0b38\u0b3e\u0b30\u0b47 \u0b2a\u0b4b\u0b24\u0b3f \u0b2a\u0b15\u0b3e\u0b07\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0964 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b26\u0b47\u0b36\u0b30\u0b47 \u0b13 \u0b30\u0b3e\u0b1c\u0b4d\u0b5f\u0b30\u0b47 \u0b2c\u0b22\u0b3f\u0b2c\u0b3e\u0b30\u0b47 \u0b32\u0b3e\u0b17\u0b3f\u0b1b\u0b3f \u0964 \u0b2c\u0b3f\u0b1c\u0b47\u0b21\u0b3f \u0b20\u0b3f\u0b15\u0b4d \u0b2d\u0b3e\u0b2c\u0b47 \u0b2e\u0b41\u0b16\u0b4d\u0b5f \u0b2c\u0b3f\u0b30\u0b4b\u0b27\u0b40\u0b26\u0b33\u0b30 \u0b2d\u0b42\u0b2e\u0b3f\u0b15\u0b3e \u0b28 \u0b28\u0b47\u0b32\u0b47 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b06\u0b17\u0b15\u0b41 \u0b2c\u0b22\u0b3c\u0b3f\u0b2f\u0b3f\u0b2c\u0b3e \u0b06\u0b36\u0b19\u0b4d\u0b15\u0b3e \u0b15\u0b30\u0b3f\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0964 \u0b32\u0b4b\u0b15\u0b47 \u0b05\u0b28\u0b41\u0b2d\u0b2c \u0b15\u0b30\u0b41\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0b2f\u0b47 \u0b2c\u0b3f\u0b1c\u0b47\u0b21\u0b3f \u0b13 \u0b2c\u0b3f\u0b1c\u0b47\u0b2a\u0b3f \u0b2d\u0b3f\u0b24\u0b30\u0b47 \u0b15\u0b3f\u0b1b\u0b3f \u0b2a\u0b4d\u0b30\u0b2d\u0b47\u0b26 \u0b28\u0b3e\u0b39\u0b3f\u0b01 \u0964 \u0b24\u0b47\u0b23\u0b41 \u0b32\u0b4b\u0b15 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b15\u0b25\u0b3e \u0b1a\u0b3f\u0b28\u0b4d\u0b24\u0b3e \u0b15\u0b32\u0b47\u0b23\u0b3f \u0964 \u0b32\u0b4b\u0b15\u0b47 \u0b2c\u0b3f\u0b30\u0b4b\u0b27\u0b40\u0b26\u0b33\u0b20\u0b41 \u0b2f\u0b3e\u0b39\u0b3e \u0b06\u0b36\u0b3e \u0b15\u0b30\u0b41\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0b24\u0b3e\u0b39\u0b3e \u0b2c\u0b3f\u0b1c\u0b47\u0b21\u0b3f\u0b20\u0b3e\u0b30\u0b41 \u0b2a\u0b3e\u0b09 \u0b28\u0b25\u0b3f\u0b2c\u0b3e \u0b15\u0b39\u0b3f\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0964<br>\u0b0f\u0b20\u0b3e\u0b30\u0b47 \u0b09\u0b32\u0b4d\u0b32\u0b47\u0b16 \u0b2f\u0b4b\u0b17\u0b4d\u0b5f, \u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b2a\u0b4d\u0b30\u0b25\u0b2e\u0b47 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b26\u0b33\u0b30\u0b47 \u0b2c\u0b3f\u0b27\u0b3e\u0b5f\u0b15 \u0b0f\u0b2c\u0b02 \u0b38\u0b3e\u0b02\u0b38\u0b26 \u0b30\u0b39\u0b3f\u0b38\u0b3e\u0b30\u0b3f\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0964 \u0b68\u0b66\u0b67\u0b6a\u0b30\u0b47 \u0b38\u0b47 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b1b\u0b3e\u0b21\u0b3c\u0b3f \u0b2c\u0b3f\u0b1c\u0b47\u0b21\u0b3c\u0b3f\u0b30\u0b47 \u0b2f\u0b4b\u0b17 \u0b26\u0b47\u0b07\u0b25\u0b3f\u0b32\u0b47 \u0964 \u0b68\u0b66\u0b67\u0b6f\u0b30\u0b47 \u0b2e\u0b27\u0b4d\u0b5f \u0b2c\u0b3f\u0b1c\u0b47\u0b21\u0b3c\u0b3f\u0b30\u0b41 \u0b1f\u0b3f\u0b15\u0b47\u0b1f\u0b4d \u0b2a\u0b3e\u0b07 \u0b2c\u0b3f\u0b27\u0b3e\u0b5f\u0b15 \u0b39\u0b4b\u0b07\u0b25\u0b3f\u0b32\u0b47 \u0964 \u0b15\u0b3f\u0b28\u0b4d\u0b24\u0b41 \u0b68\u0b66\u0b68\u0b6a \u0b28\u0b3f\u0b30\u0b4d\u0b2c\u0b3e\u0b1a\u0b28 \u0b2c\u0b47\u0b33\u0b47 \u0b26\u0b33 \u0b24\u0b3e\u0b19\u0b4d\u0b15\u0b41 \u0b05\u0b23\u0b26\u0b47\u0b16\u0b3e \u0b15\u0b30\u0b3f\u0b25\u0b3f\u0b32\u0b3e \u0964 \u0b24\u0b47\u0b2c\u0b47 \u0b2c\u0b3f\u0b1c\u0b47\u0b21\u0b3c\u0b3f\u0b30\u0b47 \u0b2c\u0b30\u0b4d\u0b24\u0b4d\u0b24\u0b2e\u0b3e\u0b28 \u0b2a\u0b3e\u0b23\u0b4d\u0b21\u0b3f\u0b06\u0b28\u0b4d \u0b30\u0b3e\u0b1c\u0b41\u0b24\u0b3f \u0b1a\u0b3e\u0b32\u0b41\u0b25\u0b3f\u0b2c\u0b3e\u0b2c\u0b47\u0b33\u0b47 \u0b05\u0b28\u0b47\u0b15 \u0b2c\u0b30\u0b3f\u0b37\u0b4d\u0b20 \u0b28\u0b47\u0b24\u0b3e \u0b05\u0b38\u0b28\u0b4d\u0b24\u0b41\u0b37\u0b4d\u0b1f \u0b25\u0b3f\u0b2c\u0b3e \u0b1a\u0b30\u0b4d\u0b1a\u0b4d\u0b1a\u0b3e \u0b39\u0b47\u0b09\u0b1b\u0b3f \u0964 \u0b38\u0b47\u0b2a\u0b1f\u0b47 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b2e\u0b27\u0b4d\u0b5f \u0b24\u0b3e\u0b30 \u0b2a\u0b41\u0b30\u0b41\u0b23\u0b3e \u0b28\u0b47\u0b24\u0b3e\u0b19\u0b4d\u0b15\u0b41 \u0b2a\u0b41\u0b23\u0b3f \u0b25\u0b30\u0b47 \u0b38\u0b4d\u0b71\u0b3e\u0b17\u0b24 \u0b15\u0b30\u0b3f\u0b2c \u0b2c\u0b4b\u0b32\u0b3f \u0b15\u0b39\u0b3f\u0b38\u0b3e\u0b30\u0b3f\u0b1b\u0b3f \u0964 \u0b2f\u0b47\u0b09\u0b01\u0b2e\u0b3e\u0b28\u0b47 \u0b2a\u0b41\u0b28\u0b30\u0b4d\u0b2c\u0b3e\u0b30 \u0b26\u0b33\u0b15\u0b41 \u0b2b\u0b47\u0b30\u0b3f\u0b2c\u0b3e\u0b15\u0b41 \u0b1a\u0b3e\u0b39\u0b41\u0b01\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0b24\u0b3e\u0b19\u0b4d\u0b15 \u0b26\u0b4d\u0b71\u0b3e\u0b30\u0b3e \u0b16\u0b4b\u0b32\u0b3e\u0b25\u0b3f\u0b2c\u0b3e\u0b2c\u0b3e \u0b05\u0b28\u0b47\u0b15 \u0b28\u0b47\u0b24\u0b3e \u0b15\u0b39\u0b3f\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0964<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0b2d\u0b41\u0b2c\u0b28\u0b47\u0b36\u0b4d\u0b71\u0b30, \u0b69\/\u0b6f : \u0b2c\u0b3f\u0b1c\u0b41 \u0b1c\u0b28\u0b24\u0b3e \u0b26\u0b33\u0b30 \u0b2c\u0b30\u0b3f\u0b37\u0b4d\u0b20 \u0b28\u0b47\u0b24\u0b3e \u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02 \u0b2a\u0b41\u0b23\u0b3f \u0b25\u0b30\u0b47 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b06\u0b21\u0b3c\u0b41\u0b15 \u0b22\u0b33\u0b41\u0b25\u0b3f\u0b2c\u0b3e \u0b2a\u0b4d\u0b30\u0b24\u0b40\u0b5f\u0b2e\u0b3e\u0b28 \u0b39\u0b47\u0b09\u0b1b\u0b3f \u0964 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b18\u0b30 \u0b2c\u0b3e\u0b39\u0b41\u0b21\u0b3c\u0b3e \u0b15\u0b30\u0b3f\u0b2c\u0b3e\u0b15\u0b41 \u0b38\u0b19\u0b4d\u0b15\u0b47\u0b24 \u0b26\u0b47\u0b32\u0b47\u0b23\u0b3f \u0964 \u0b24\u0b3e\u0b19\u0b4d\u0b15 \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15\u0b47 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20 \u0b26\u0b33<\/p>\n","protected":false},"author":1,"featured_media":141473,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[882],"tags":[77,66],"class_list":["post-141472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-odia-news","tag-bhubaneswar","tag-odisha"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15 \u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15 \u0b2c\u0b5f\u0b3e\u0b28 : \u0b15\u0b39\u0b3f\u0b32\u0b47- \u0b2e\u0b4b \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15 \u0b39\u0b3f\u0b01 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20, \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01 - Indus Valley Times<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/indusvalleytimes.com\/news\/\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30-\u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15-\u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15 \u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15 \u0b2c\u0b5f\u0b3e\u0b28 : \u0b15\u0b39\u0b3f\u0b32\u0b47- \u0b2e\u0b4b \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15 \u0b39\u0b3f\u0b01 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20, \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01 - Indus Valley Times\" \/>\n<meta property=\"og:description\" content=\"\u0b2d\u0b41\u0b2c\u0b28\u0b47\u0b36\u0b4d\u0b71\u0b30, \u0b69\/\u0b6f : \u0b2c\u0b3f\u0b1c\u0b41 \u0b1c\u0b28\u0b24\u0b3e \u0b26\u0b33\u0b30 \u0b2c\u0b30\u0b3f\u0b37\u0b4d\u0b20 \u0b28\u0b47\u0b24\u0b3e \u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02 \u0b2a\u0b41\u0b23\u0b3f \u0b25\u0b30\u0b47 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b06\u0b21\u0b3c\u0b41\u0b15 \u0b22\u0b33\u0b41\u0b25\u0b3f\u0b2c\u0b3e \u0b2a\u0b4d\u0b30\u0b24\u0b40\u0b5f\u0b2e\u0b3e\u0b28 \u0b39\u0b47\u0b09\u0b1b\u0b3f \u0964 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b18\u0b30 \u0b2c\u0b3e\u0b39\u0b41\u0b21\u0b3c\u0b3e \u0b15\u0b30\u0b3f\u0b2c\u0b3e\u0b15\u0b41 \u0b38\u0b19\u0b4d\u0b15\u0b47\u0b24 \u0b26\u0b47\u0b32\u0b47\u0b23\u0b3f \u0964 \u0b24\u0b3e\u0b19\u0b4d\u0b15 \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15\u0b47 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20 \u0b26\u0b33\" \/>\n<meta property=\"og:url\" content=\"http:\/\/indusvalleytimes.com\/news\/\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30-\u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15-\u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15\/\" \/>\n<meta property=\"og:site_name\" content=\"Indus Valley Times\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-03T12:16:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T12:16:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/indusvalleytimes.com\/news\/wp-content\/uploads\/2025\/09\/congress.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"628\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"indadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"indadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\\\/\"},\"author\":{\"name\":\"indadmin\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#\\\/schema\\\/person\\\/229ac2ee13eea90327e2e7301c3ef206\"},\"headline\":\"\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15 \u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15 \u0b2c\u0b5f\u0b3e\u0b28 : \u0b15\u0b39\u0b3f\u0b32\u0b47- \u0b2e\u0b4b \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15 \u0b39\u0b3f\u0b01 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20, \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01\",\"datePublished\":\"2025-09-03T12:16:34+00:00\",\"dateModified\":\"2025-09-03T12:16:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\\\/\"},\"wordCount\":1,\"publisher\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/congress.jpeg\",\"keywords\":[\"Bhubaneswar\",\"Odisha\"],\"articleSection\":[\"Odia News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\\\/\",\"url\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\\\/\",\"name\":\"\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15 \u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15 \u0b2c\u0b5f\u0b3e\u0b28 : \u0b15\u0b39\u0b3f\u0b32\u0b47- \u0b2e\u0b4b \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15 \u0b39\u0b3f\u0b01 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20, \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01 - Indus Valley Times\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/congress.jpeg\",\"datePublished\":\"2025-09-03T12:16:34+00:00\",\"dateModified\":\"2025-09-03T12:16:35+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\\\/#primaryimage\",\"url\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/congress.jpeg\",\"contentUrl\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/congress.jpeg\",\"width\":628,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15 \u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15 \u0b2c\u0b5f\u0b3e\u0b28 : \u0b15\u0b39\u0b3f\u0b32\u0b47- \u0b2e\u0b4b \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15 \u0b39\u0b3f\u0b01 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20, \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#website\",\"url\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/\",\"name\":\"Indus Valley Times\",\"description\":\"Leading Newspaper of Odisha\",\"publisher\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#organization\",\"name\":\"Indus Valley Times\",\"url\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/logo.png\",\"contentUrl\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/logo.png\",\"width\":440,\"height\":111,\"caption\":\"Indus Valley Times\"},\"image\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#\\\/schema\\\/person\\\/229ac2ee13eea90327e2e7301c3ef206\",\"name\":\"indadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b6f9b03321fc8effd1d678eb205a8c244bf8b1ceb3282aa64a44cda4666e3ea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b6f9b03321fc8effd1d678eb205a8c244bf8b1ceb3282aa64a44cda4666e3ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b6f9b03321fc8effd1d678eb205a8c244bf8b1ceb3282aa64a44cda4666e3ea?s=96&d=mm&r=g\",\"caption\":\"indadmin\"},\"url\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/author\\\/indadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15 \u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15 \u0b2c\u0b5f\u0b3e\u0b28 : \u0b15\u0b39\u0b3f\u0b32\u0b47- \u0b2e\u0b4b \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15 \u0b39\u0b3f\u0b01 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20, \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01 - Indus Valley Times","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/indusvalleytimes.com\/news\/\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30-\u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15-\u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15\/","og_locale":"en_US","og_type":"article","og_title":"\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15 \u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15 \u0b2c\u0b5f\u0b3e\u0b28 : \u0b15\u0b39\u0b3f\u0b32\u0b47- \u0b2e\u0b4b \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15 \u0b39\u0b3f\u0b01 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20, \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01 - Indus Valley Times","og_description":"\u0b2d\u0b41\u0b2c\u0b28\u0b47\u0b36\u0b4d\u0b71\u0b30, \u0b69\/\u0b6f : \u0b2c\u0b3f\u0b1c\u0b41 \u0b1c\u0b28\u0b24\u0b3e \u0b26\u0b33\u0b30 \u0b2c\u0b30\u0b3f\u0b37\u0b4d\u0b20 \u0b28\u0b47\u0b24\u0b3e \u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02 \u0b2a\u0b41\u0b23\u0b3f \u0b25\u0b30\u0b47 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b06\u0b21\u0b3c\u0b41\u0b15 \u0b22\u0b33\u0b41\u0b25\u0b3f\u0b2c\u0b3e \u0b2a\u0b4d\u0b30\u0b24\u0b40\u0b5f\u0b2e\u0b3e\u0b28 \u0b39\u0b47\u0b09\u0b1b\u0b3f \u0964 \u0b15\u0b02\u0b17\u0b4d\u0b30\u0b47\u0b38 \u0b18\u0b30 \u0b2c\u0b3e\u0b39\u0b41\u0b21\u0b3c\u0b3e \u0b15\u0b30\u0b3f\u0b2c\u0b3e\u0b15\u0b41 \u0b38\u0b19\u0b4d\u0b15\u0b47\u0b24 \u0b26\u0b47\u0b32\u0b47\u0b23\u0b3f \u0964 \u0b24\u0b3e\u0b19\u0b4d\u0b15 \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15\u0b47 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20 \u0b26\u0b33","og_url":"http:\/\/indusvalleytimes.com\/news\/\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30-\u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15-\u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15\/","og_site_name":"Indus Valley Times","article_published_time":"2025-09-03T12:16:34+00:00","article_modified_time":"2025-09-03T12:16:35+00:00","og_image":[{"width":628,"height":340,"url":"http:\/\/indusvalleytimes.com\/news\/wp-content\/uploads\/2025\/09\/congress.jpeg","type":"image\/jpeg"}],"author":"indadmin","twitter_misc":{"Written by":"indadmin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/#article","isPartOf":{"@id":"http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/"},"author":{"name":"indadmin","@id":"http:\/\/indusvalleytimes.com\/news\/#\/schema\/person\/229ac2ee13eea90327e2e7301c3ef206"},"headline":"\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15 \u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15 \u0b2c\u0b5f\u0b3e\u0b28 : \u0b15\u0b39\u0b3f\u0b32\u0b47- \u0b2e\u0b4b \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15 \u0b39\u0b3f\u0b01 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20, \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01","datePublished":"2025-09-03T12:16:34+00:00","dateModified":"2025-09-03T12:16:35+00:00","mainEntityOfPage":{"@id":"http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/"},"wordCount":1,"publisher":{"@id":"http:\/\/indusvalleytimes.com\/news\/#organization"},"image":{"@id":"http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/#primaryimage"},"thumbnailUrl":"http:\/\/indusvalleytimes.com\/news\/wp-content\/uploads\/2025\/09\/congress.jpeg","keywords":["Bhubaneswar","Odisha"],"articleSection":["Odia News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/","url":"http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/","name":"\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15 \u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15 \u0b2c\u0b5f\u0b3e\u0b28 : \u0b15\u0b39\u0b3f\u0b32\u0b47- \u0b2e\u0b4b \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15 \u0b39\u0b3f\u0b01 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20, \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01 - Indus Valley Times","isPartOf":{"@id":"http:\/\/indusvalleytimes.com\/news\/#website"},"primaryImageOfPage":{"@id":"http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/#primaryimage"},"image":{"@id":"http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/#primaryimage"},"thumbnailUrl":"http:\/\/indusvalleytimes.com\/news\/wp-content\/uploads\/2025\/09\/congress.jpeg","datePublished":"2025-09-03T12:16:34+00:00","dateModified":"2025-09-03T12:16:35+00:00","breadcrumb":{"@id":"http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/#primaryimage","url":"http:\/\/indusvalleytimes.com\/news\/wp-content\/uploads\/2025\/09\/congress.jpeg","contentUrl":"http:\/\/indusvalleytimes.com\/news\/wp-content\/uploads\/2025\/09\/congress.jpeg","width":628,"height":340},{"@type":"BreadcrumbList","@id":"http:\/\/indusvalleytimes.com\/news\/%e0%ac%ad%e0%ad%82%e0%ac%aa%e0%ac%bf%e0%ac%a8%e0%ad%8d%e0%ac%a6%e0%ac%b0-%e0%ac%b8%e0%ac%bf%e0%ac%82%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%ac%e0%ac%bf%e0%ac%b8%e0%ad%8d%e0%ac%ab%e0%ad%8b%e0%ac%b0%e0%ac%95\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/indusvalleytimes.com\/news\/"},{"@type":"ListItem","position":2,"name":"\u0b2d\u0b42\u0b2a\u0b3f\u0b28\u0b4d\u0b26\u0b30 \u0b38\u0b3f\u0b02\u0b19\u0b4d\u0b15 \u0b2c\u0b3f\u0b38\u0b4d\u0b2b\u0b4b\u0b30\u0b15 \u0b2c\u0b5f\u0b3e\u0b28 : \u0b15\u0b39\u0b3f\u0b32\u0b47- \u0b2e\u0b4b \u0b2a\u0b3e\u0b07\u0b01 \u0b32\u0b4b\u0b15 \u0b39\u0b3f\u0b01 \u0b36\u0b4d\u0b30\u0b47\u0b37\u0b4d\u0b20, \u0b26\u0b33 \u0b28\u0b41\u0b39\u0b47\u0b01"}]},{"@type":"WebSite","@id":"http:\/\/indusvalleytimes.com\/news\/#website","url":"http:\/\/indusvalleytimes.com\/news\/","name":"Indus Valley Times","description":"Leading Newspaper of Odisha","publisher":{"@id":"http:\/\/indusvalleytimes.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/indusvalleytimes.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/indusvalleytimes.com\/news\/#organization","name":"Indus Valley Times","url":"http:\/\/indusvalleytimes.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/indusvalleytimes.com\/news\/#\/schema\/logo\/image\/","url":"http:\/\/indusvalleytimes.com\/news\/wp-content\/uploads\/2015\/07\/logo.png","contentUrl":"http:\/\/indusvalleytimes.com\/news\/wp-content\/uploads\/2015\/07\/logo.png","width":440,"height":111,"caption":"Indus Valley Times"},"image":{"@id":"http:\/\/indusvalleytimes.com\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/indusvalleytimes.com\/news\/#\/schema\/person\/229ac2ee13eea90327e2e7301c3ef206","name":"indadmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9b6f9b03321fc8effd1d678eb205a8c244bf8b1ceb3282aa64a44cda4666e3ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9b6f9b03321fc8effd1d678eb205a8c244bf8b1ceb3282aa64a44cda4666e3ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9b6f9b03321fc8effd1d678eb205a8c244bf8b1ceb3282aa64a44cda4666e3ea?s=96&d=mm&r=g","caption":"indadmin"},"url":"http:\/\/indusvalleytimes.com\/news\/author\/indadmin\/"}]}},"jetpack_featured_media_url":"http:\/\/indusvalleytimes.com\/news\/wp-content\/uploads\/2025\/09\/congress.jpeg","_links":{"self":[{"href":"http:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/posts\/141472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/comments?post=141472"}],"version-history":[{"count":1,"href":"http:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/posts\/141472\/revisions"}],"predecessor-version":[{"id":141474,"href":"http:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/posts\/141472\/revisions\/141474"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/media\/141473"}],"wp:attachment":[{"href":"http:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/media?parent=141472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/categories?post=141472"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/tags?post=141472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}