{"id":34152,"date":"2019-12-04T13:35:54","date_gmt":"2019-12-04T08:05:54","guid":{"rendered":"http:\/\/indusvalleytimes.com\/news\/?p=34152"},"modified":"2019-12-04T13:36:05","modified_gmt":"2019-12-04T08:06:05","slug":"%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7","status":"publish","type":"post","link":"https:\/\/indusvalleytimes.com\/news\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\/","title":{"rendered":"\u0b69\u0b67\u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15 \u0b20\u0b3e\u0b30\u0b41 \u0b68\u0b67\u0b67\u0b6f\u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28  \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39"},"content":{"rendered":"\n<p class=\"caps\">  \u0b17\u0b24\u0b2c\u0b30\u0b4d\u0b37  \u0b24\u0b41\u0b33\u0b28\u0b3e\u0b30\u0b47 \u0b67\u0b69 \u0b2a\u0b4d\u0b30\u0b24\u0b3f\u0b36\u0b24 \u0b05\u0b27\u0b3f\u0b15 <br> \u0b2d\u0b41\u0b2c\u0b28\u0b47\u0b36\u0b4d\u0b71\u0b30,\u0b6a \u0964\u0b67\u0b67:  \u0b30\u0b3e\u0b1c\u0b4d\u0b5f \u0b38\u0b30\u0b15\u0b3e\u0b30\u0b19\u0b4d\u0b15 \u0b26\u0b4d\u0b71\u0b3e\u0b30\u0b3e \u0b16\u0b30\u0b3f\u0b2b\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 \u0b2c\u0b30\u0b4d\u0b37 \u0b68\u0b66\u0b67\u0b6f-\u0b68\u0b66\u0b30\u0b47 \u0b06\u0b1c\u0b3f \u0b38\u0b41\u0b26\u0b4d\u0b27\u0b3e \u0b69\u0b67 \u0b39\u0b1c\u0b3e\u0b30 \u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40 \u0b2e\u0b4b\u0b1f \u0b68\u0b67 \u0b32\u0b15\u0b4d\u0b37 \u0b67\u0b6f \u0b39\u0b1c\u0b3e\u0b30 \u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b2c\u0b3f\u0b2d\u0b3f\u0b28\u0b4d\u0b28 \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 \u0b15\u0b47\u0b28\u0b4d\u0b26\u0b4d\u0b30\u0b30\u0b47 \u0b2c\u0b3f\u0b15\u0b4d\u0b30\u0b3f \u0b15\u0b30\u0b3f\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0b2f\u0b3e\u0b39\u0b3e\u0b15\u0b3f \u0b17\u0b24\u0b2c\u0b30\u0b4d\u0b37 \u0b06\u0b1c\u0b3f\u0b30 \u0b26\u0b3f\u0b28\u0b20\u0b3e\u0b30\u0b41 \u0b67\u0b69 \u0b2a\u0b4d\u0b30\u0b24\u0b3f\u0b36\u0b24 \u0b05\u0b27\u0b3f\u0b15 \u0964 \u0b17\u0b24 \u0b68\u0b66\u0b67\u0b6e \u0b21\u0b3f\u0b38\u0b47\u0b2e\u0b4d\u0b2c\u0b30 \u0b69 \u0b24\u0b3e\u0b30\u0b3f\u0b16 \u0b38\u0b41\u0b26\u0b4d\u0b27\u0b3e \u0b2e\u0b4b\u0b1f \u0b67\u0b6e \u0b32\u0b15\u0b4d\u0b37 \u0b6d\u0b6e \u0b39\u0b1c\u0b3e\u0b30 \u0b6e\u0b6d\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 \u0b39\u0b4b\u0b07\u0b25\u0b3f\u0b32\u0b3e \u0964<br> \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 \u0b15\u0b3e\u0b30\u0b4d\u0b2f\u0b4d\u0b5f\u0b15\u0b41 \u0b38\u0b4d\u0b71\u0b1a\u0b4d\u0b1b \u0b13 \u0b2c\u0b4d\u0b5f\u0b2c\u0b38\u0b4d\u0b25\u0b3f\u0b24 \u0b15\u0b30\u0b3f\u0b2c\u0b3e \u0b2a\u0b3e\u0b07\u0b01 \u0b05\u0b28\u0b4d\u0b32\u0b3e\u0b07\u0b28\u0b4d\u0b30\u0b47 \u0b2a\u0b1e\u0b4d\u0b1c\u0b40\u0b15\u0b43\u0b24 \u0b1a\u0b3e\u0b37\u0b40\u0b2e\u0b3e\u0b28\u0b19\u0b4d\u0b15\u0b41 \u0b06\u0b17\u0b41\u0b06 \u0b1f\u0b4b\u0b15\u0b47\u0b28\u0b4d \u0b2c\u0b4d\u0b5f\u0b2c\u0b38\u0b4d\u0b25\u0b3e\u0b30\u0b47 \u0b2a\u0b3f-\u0b2a\u0b3e\u0b38\u0b4d \u0b1c\u0b30\u0b3f\u0b06\u0b30\u0b47 \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 \u0b15\u0b30\u0b3e\u0b2f\u0b3e\u0b09\u0b1b\u0b3f \u0964 \u0b2c\u0b30\u0b4d\u0b24\u0b2e\u0b3e\u0b28 \u0b38\u0b41\u0b26\u0b4d\u0b27\u0b3e \u0b67\u0b6d\u0b1f\u0b3f \u0b1c\u0b3f\u0b32\u0b4d\u0b32\u0b3e\u0b30\u0b47 \u0b6f\u0b6c\u0b6c\u0b1f\u0b3f \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 \u0b15\u0b47\u0b28\u0b4d\u0b26\u0b4d\u0b30\u0b30\u0b41 \u0b67 \u0b32\u0b15\u0b4d\u0b37 \u0b6b\u0b68 \u0b39\u0b1c\u0b3e\u0b30 \u0b6f\u0b6d\u0b6b \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15\u0b41 \u0b68 \u0b32\u0b15\u0b4d\u0b37 \u0b6b \u0b39\u0b1c\u0b3e\u0b30 \u0b6c\u0b66\u0b67 \u0b1f\u0b3f \u0b06\u0b17\u0b41\u0b06 \u0b1f\u0b4b\u0b15\u0b47\u0b28\u0b4d \u0b26\u0b3f\u0b06\u0b2f\u0b3e\u0b07\u0b1b\u0b3f \u0964 <br> \u0b05\u0b27\u0b3f\u0b15 \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 \u0b39\u0b4b\u0b07\u0b25\u0b3f\u0b2c\u0b3e \u0b1c\u0b3f\u0b32\u0b4d\u0b32\u0b3e\u0b17\u0b41\u0b5c\u0b3f\u0b15 \u0b2e\u0b27\u0b4d\u0b5f\u0b30\u0b47 \u0b2c\u0b30\u0b17\u0b5c \u0b1c\u0b3f\u0b32\u0b4d\u0b32\u0b3e\u0b30\u0b47 \u0b67\u0b6c \u0b39\u0b1c\u0b3e\u0b30 \u0b68\u0b69 \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40 \u0b67\u0b67 \u0b32\u0b15\u0b4d\u0b37 \u0b69\u0b6e \u0b39\u0b1c\u0b3e\u0b30 \u0b6c\u0b67\u0b6c \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b2c\u0b3f\u0b15\u0b4d\u0b30\u0b3f \u0b15\u0b30\u0b3f\u0b25\u0b3f\u0b2c\u0b3e\u0b2c\u0b47\u0b33\u0b47 \u0b2c\u0b32\u0b3e\u0b19\u0b4d\u0b17\u0b40\u0b30 \u0b1c\u0b3f\u0b32\u0b4d\u0b32\u0b3e\u0b30 \u0b68\u0b66\u0b6d\u0b6d \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40 \u0b67 \u0b32\u0b15\u0b4d\u0b37 \u0b6a\u0b6c \u0b39\u0b1c\u0b3e\u0b30 \u0b6b\u0b6f \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d, \u0b15\u0b33\u0b3e\u0b39\u0b3e\u0b23\u0b4d\u0b21\u0b3f \u0b1c\u0b3f\u0b32\u0b4d\u0b32\u0b3e\u0b30 \u0b69\u0b6b\u0b66\u0b6b \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40 \u0b68 \u0b32\u0b15\u0b4d\u0b37 \u0b69\u0b68 \u0b39\u0b1c\u0b3e\u0b30 \u0b6c\u0b67\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d, \u0b2e\u0b3e\u0b32\u0b15\u0b3e\u0b28\u0b17\u0b3f\u0b30\u0b3f\u0b30 \u0b68\u0b6e\u0b6d\u0b6d \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40 \u0b67 \u0b32\u0b15\u0b4d\u0b37 \u0b6b \u0b39\u0b1c\u0b3e\u0b30 \u0b6f\u0b6b\u0b6c \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d, \u0b28\u0b42\u0b06\u0b2a\u0b5c\u0b3e \u0b1c\u0b3f\u0b32\u0b4d\u0b32\u0b3e\u0b30 \u0b67\u0b6d\u0b6e\u0b6c \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40 \u0b6c\u0b6f \u0b39\u0b1c\u0b3e\u0b30 \u0b6b\u0b6a\u0b69 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d, \u0b38\u0b2e\u0b4d\u0b2c\u0b32\u0b2a\u0b41\u0b30 \u0b1c\u0b3f\u0b32\u0b4d\u0b32\u0b3e\u0b30 \u0b68\u0b6b\u0b69\u0b6a \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40 \u0b68 \u0b32\u0b15\u0b4d\u0b37 \u0b69\u0b69 \u0b39\u0b1c\u0b3e\u0b30 \u0b6d\u0b69\u0b66 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b0f\u0b2c\u0b02 \u0b38\u0b41\u0b2c\u0b30\u0b4d\u0b23\u0b4d\u0b23\u0b2a\u0b41\u0b30 \u0b1c\u0b3f\u0b32\u0b4d\u0b32\u0b3e\u0b30 \u0b67\u0b6f\u0b68\u0b67 \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40 \u0b67 \u0b32\u0b15\u0b4d\u0b37 \u0b6c\u0b6c \u0b39\u0b1c\u0b3e\u0b30 \u0b69\u0b67\u0b6a \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b2c\u0b3f\u0b2d\u0b3f\u0b28\u0b4d\u0b28 \u0b2a\u0b4d\u0b5f\u0b3e\u0b15\u0b38\u0b4d\u0b30\u0b47 \u0b27\u0b3e\u0b28 \u0b2c\u0b3f\u0b15\u0b4d\u0b30\u0b3f \u0b15\u0b30\u0b3f\u0b1b\u0b28\u0b4d\u0b24\u0b3f \u0964 \u0b38\u0b47\u0b39\u0b3f\u0b2a\u0b30\u0b3f \u0b27\u0b3e\u0b28 \u0b2c\u0b3f\u0b15\u0b4d\u0b30\u0b3f \u0b2e\u0b42\u0b32\u0b4d\u0b5f \u0b2a\u0b4d\u0b30\u0b24\u0b4d\u0b5f\u0b15\u0b4d\u0b37 \u0b39\u0b38\u0b4d\u0b24\u0b3e\u0b28\u0b4d\u0b24\u0b30 \u0b2c\u0b4d\u0b5f\u0b2c\u0b38\u0b4d\u0b25\u0b3e\u0b30\u0b47 \u0b06\u0b1c\u0b3f \u0b38\u0b41\u0b26\u0b4d\u0b27\u0b3e \u0b68\u0b6e \u0b39\u0b1c\u0b3e\u0b30 \u0b6e\u0b66\u0b67 \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15 \u0b2c\u0b4d\u0b5f\u0b3e\u0b19\u0b4d\u0b15 \u0b05 \u0964\u0b15\u0b3e\u0b09\u0b02\u0b1f\u0b15\u0b41 \u0b69\u0b68\u0b6a \u0b15\u0b4b\u0b1f\u0b3f \u0b69\u0b6b \u0b32\u0b15\u0b4d\u0b37 \u0b6d\u0b6f \u0b39\u0b1c\u0b3e\u0b30 \u0b68\u0b6a\u0b6a \u0b1f\u0b19\u0b4d\u0b15\u0b3e \u0b2a\u0b4d\u0b30\u0b26\u0b3e\u0b28 \u0b15\u0b30\u0b3e\u0b2f\u0b3e\u0b07\u0b1b\u0b3f \u0964<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0b17\u0b24\u0b2c\u0b30\u0b4d\u0b37 \u0b24\u0b41\u0b33\u0b28\u0b3e\u0b30\u0b47 \u0b67\u0b69 \u0b2a\u0b4d\u0b30\u0b24\u0b3f\u0b36\u0b24 \u0b05\u0b27\u0b3f\u0b15 \u0b2d\u0b41\u0b2c\u0b28\u0b47\u0b36\u0b4d\u0b71\u0b30,\u0b6a \u0964\u0b67\u0b67: \u0b30\u0b3e\u0b1c\u0b4d\u0b5f \u0b38\u0b30\u0b15\u0b3e\u0b30\u0b19\u0b4d\u0b15 \u0b26\u0b4d\u0b71\u0b3e\u0b30\u0b3e \u0b16\u0b30\u0b3f\u0b2b\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 \u0b2c\u0b30\u0b4d\u0b37 \u0b68\u0b66\u0b67\u0b6f-\u0b68\u0b66\u0b30\u0b47 \u0b06\u0b1c\u0b3f \u0b38\u0b41\u0b26\u0b4d\u0b27\u0b3e \u0b69\u0b67 \u0b39\u0b1c\u0b3e\u0b30 \u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40 \u0b2e\u0b4b\u0b1f \u0b68\u0b67 \u0b32\u0b15\u0b4d\u0b37 \u0b67\u0b6f \u0b39\u0b1c\u0b3e\u0b30 \u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[882],"tags":[],"class_list":["post-34152","post","type-post","status-publish","format-standard","hentry","category-odia-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0b69\u0b67\u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15 \u0b20\u0b3e\u0b30\u0b41 \u0b68\u0b67\u0b67\u0b6f\u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 - Indus Valley Times<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/indusvalleytimes.com\/news\/\u0b69\u0b67\u0b67\u0b6e\u0b6e-\u0b1c\u0b23-\u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15-\u0b20\u0b3e\u0b30\u0b41-\u0b68\u0b67\u0b67\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0b69\u0b67\u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15 \u0b20\u0b3e\u0b30\u0b41 \u0b68\u0b67\u0b67\u0b6f\u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 - Indus Valley Times\" \/>\n<meta property=\"og:description\" content=\"\u0b17\u0b24\u0b2c\u0b30\u0b4d\u0b37 \u0b24\u0b41\u0b33\u0b28\u0b3e\u0b30\u0b47 \u0b67\u0b69 \u0b2a\u0b4d\u0b30\u0b24\u0b3f\u0b36\u0b24 \u0b05\u0b27\u0b3f\u0b15 \u0b2d\u0b41\u0b2c\u0b28\u0b47\u0b36\u0b4d\u0b71\u0b30,\u0b6a \u0964\u0b67\u0b67: \u0b30\u0b3e\u0b1c\u0b4d\u0b5f \u0b38\u0b30\u0b15\u0b3e\u0b30\u0b19\u0b4d\u0b15 \u0b26\u0b4d\u0b71\u0b3e\u0b30\u0b3e \u0b16\u0b30\u0b3f\u0b2b\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 \u0b2c\u0b30\u0b4d\u0b37 \u0b68\u0b66\u0b67\u0b6f-\u0b68\u0b66\u0b30\u0b47 \u0b06\u0b1c\u0b3f \u0b38\u0b41\u0b26\u0b4d\u0b27\u0b3e \u0b69\u0b67 \u0b39\u0b1c\u0b3e\u0b30 \u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40 \u0b2e\u0b4b\u0b1f \u0b68\u0b67 \u0b32\u0b15\u0b4d\u0b37 \u0b67\u0b6f \u0b39\u0b1c\u0b3e\u0b30 \u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28\" \/>\n<meta property=\"og:url\" content=\"https:\/\/indusvalleytimes.com\/news\/\u0b69\u0b67\u0b67\u0b6e\u0b6e-\u0b1c\u0b23-\u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15-\u0b20\u0b3e\u0b30\u0b41-\u0b68\u0b67\u0b67\/\" \/>\n<meta property=\"og:site_name\" content=\"Indus Valley Times\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-04T08:05:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-04T08:06:05+00:00\" \/>\n<meta name=\"author\" content=\"indadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"indadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\\\/\"},\"author\":{\"name\":\"indadmin\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#\\\/schema\\\/person\\\/229ac2ee13eea90327e2e7301c3ef206\"},\"headline\":\"\u0b69\u0b67\u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15 \u0b20\u0b3e\u0b30\u0b41 \u0b68\u0b67\u0b67\u0b6f\u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39\",\"datePublished\":\"2019-12-04T08:05:54+00:00\",\"dateModified\":\"2019-12-04T08:06:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\\\/\"},\"wordCount\":2,\"publisher\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#organization\"},\"articleSection\":[\"Odia News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\\\/\",\"url\":\"https:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\\\/\",\"name\":\"\u0b69\u0b67\u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15 \u0b20\u0b3e\u0b30\u0b41 \u0b68\u0b67\u0b67\u0b6f\u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 - Indus Valley Times\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#website\"},\"datePublished\":\"2019-12-04T08:05:54+00:00\",\"dateModified\":\"2019-12-04T08:06:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/indusvalleytimes.com\\\/news\\\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0b69\u0b67\u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15 \u0b20\u0b3e\u0b30\u0b41 \u0b68\u0b67\u0b67\u0b6f\u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#website\",\"url\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/\",\"name\":\"Indus Valley Times\",\"description\":\"Leading Newspaper of Odisha\",\"publisher\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#organization\",\"name\":\"Indus Valley Times\",\"url\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/logo.png\",\"contentUrl\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/logo.png\",\"width\":440,\"height\":111,\"caption\":\"Indus Valley Times\"},\"image\":{\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/indusvalleytimes.com\\\/news\\\/#\\\/schema\\\/person\\\/229ac2ee13eea90327e2e7301c3ef206\",\"name\":\"indadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b6f9b03321fc8effd1d678eb205a8c244bf8b1ceb3282aa64a44cda4666e3ea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b6f9b03321fc8effd1d678eb205a8c244bf8b1ceb3282aa64a44cda4666e3ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b6f9b03321fc8effd1d678eb205a8c244bf8b1ceb3282aa64a44cda4666e3ea?s=96&d=mm&r=g\",\"caption\":\"indadmin\"},\"url\":\"https:\\\/\\\/indusvalleytimes.com\\\/news\\\/author\\\/indadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0b69\u0b67\u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15 \u0b20\u0b3e\u0b30\u0b41 \u0b68\u0b67\u0b67\u0b6f\u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 - Indus Valley Times","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/indusvalleytimes.com\/news\/\u0b69\u0b67\u0b67\u0b6e\u0b6e-\u0b1c\u0b23-\u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15-\u0b20\u0b3e\u0b30\u0b41-\u0b68\u0b67\u0b67\/","og_locale":"en_US","og_type":"article","og_title":"\u0b69\u0b67\u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15 \u0b20\u0b3e\u0b30\u0b41 \u0b68\u0b67\u0b67\u0b6f\u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 - Indus Valley Times","og_description":"\u0b17\u0b24\u0b2c\u0b30\u0b4d\u0b37 \u0b24\u0b41\u0b33\u0b28\u0b3e\u0b30\u0b47 \u0b67\u0b69 \u0b2a\u0b4d\u0b30\u0b24\u0b3f\u0b36\u0b24 \u0b05\u0b27\u0b3f\u0b15 \u0b2d\u0b41\u0b2c\u0b28\u0b47\u0b36\u0b4d\u0b71\u0b30,\u0b6a \u0964\u0b67\u0b67: \u0b30\u0b3e\u0b1c\u0b4d\u0b5f \u0b38\u0b30\u0b15\u0b3e\u0b30\u0b19\u0b4d\u0b15 \u0b26\u0b4d\u0b71\u0b3e\u0b30\u0b3e \u0b16\u0b30\u0b3f\u0b2b\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 \u0b2c\u0b30\u0b4d\u0b37 \u0b68\u0b66\u0b67\u0b6f-\u0b68\u0b66\u0b30\u0b47 \u0b06\u0b1c\u0b3f \u0b38\u0b41\u0b26\u0b4d\u0b27\u0b3e \u0b69\u0b67 \u0b39\u0b1c\u0b3e\u0b30 \u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40 \u0b2e\u0b4b\u0b1f \u0b68\u0b67 \u0b32\u0b15\u0b4d\u0b37 \u0b67\u0b6f \u0b39\u0b1c\u0b3e\u0b30 \u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28","og_url":"https:\/\/indusvalleytimes.com\/news\/\u0b69\u0b67\u0b67\u0b6e\u0b6e-\u0b1c\u0b23-\u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15-\u0b20\u0b3e\u0b30\u0b41-\u0b68\u0b67\u0b67\/","og_site_name":"Indus Valley Times","article_published_time":"2019-12-04T08:05:54+00:00","article_modified_time":"2019-12-04T08:06:05+00:00","author":"indadmin","twitter_misc":{"Written by":"indadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/indusvalleytimes.com\/news\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\/#article","isPartOf":{"@id":"https:\/\/indusvalleytimes.com\/news\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\/"},"author":{"name":"indadmin","@id":"http:\/\/indusvalleytimes.com\/news\/#\/schema\/person\/229ac2ee13eea90327e2e7301c3ef206"},"headline":"\u0b69\u0b67\u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15 \u0b20\u0b3e\u0b30\u0b41 \u0b68\u0b67\u0b67\u0b6f\u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39","datePublished":"2019-12-04T08:05:54+00:00","dateModified":"2019-12-04T08:06:05+00:00","mainEntityOfPage":{"@id":"https:\/\/indusvalleytimes.com\/news\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\/"},"wordCount":2,"publisher":{"@id":"http:\/\/indusvalleytimes.com\/news\/#organization"},"articleSection":["Odia News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/indusvalleytimes.com\/news\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\/","url":"https:\/\/indusvalleytimes.com\/news\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\/","name":"\u0b69\u0b67\u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15 \u0b20\u0b3e\u0b30\u0b41 \u0b68\u0b67\u0b67\u0b6f\u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39 - Indus Valley Times","isPartOf":{"@id":"http:\/\/indusvalleytimes.com\/news\/#website"},"datePublished":"2019-12-04T08:05:54+00:00","dateModified":"2019-12-04T08:06:05+00:00","breadcrumb":{"@id":"https:\/\/indusvalleytimes.com\/news\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/indusvalleytimes.com\/news\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/indusvalleytimes.com\/news\/%e0%ad%a9%e0%ad%a7%e0%ad%a7%e0%ad%ae%e0%ad%ae-%e0%ac%9c%e0%ac%a3-%e0%ac%9a%e0%ac%be%e0%ac%b7%e0%ad%80%e0%ac%99%e0%ad%8d%e0%ac%95-%e0%ac%a0%e0%ac%be%e0%ac%b0%e0%ad%81-%e0%ad%a8%e0%ad%a7%e0%ad%a7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/indusvalleytimes.com\/news\/"},{"@type":"ListItem","position":2,"name":"\u0b69\u0b67\u0b67\u0b6e\u0b6e \u0b1c\u0b23 \u0b1a\u0b3e\u0b37\u0b40\u0b19\u0b4d\u0b15 \u0b20\u0b3e\u0b30\u0b41 \u0b68\u0b67\u0b67\u0b6f\u0b6b\u0b66\u0b67 \u0b15\u0b4d\u0b71\u0b3f\u0b02\u0b1f\u0b3e\u0b32\u0b4d \u0b27\u0b3e\u0b28 \u0b38\u0b02\u0b17\u0b4d\u0b30\u0b39"}]},{"@type":"WebSite","@id":"http:\/\/indusvalleytimes.com\/news\/#website","url":"http:\/\/indusvalleytimes.com\/news\/","name":"Indus Valley Times","description":"Leading Newspaper of Odisha","publisher":{"@id":"http:\/\/indusvalleytimes.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/indusvalleytimes.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/indusvalleytimes.com\/news\/#organization","name":"Indus Valley Times","url":"http:\/\/indusvalleytimes.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/indusvalleytimes.com\/news\/#\/schema\/logo\/image\/","url":"http:\/\/indusvalleytimes.com\/news\/wp-content\/uploads\/2015\/07\/logo.png","contentUrl":"http:\/\/indusvalleytimes.com\/news\/wp-content\/uploads\/2015\/07\/logo.png","width":440,"height":111,"caption":"Indus Valley Times"},"image":{"@id":"http:\/\/indusvalleytimes.com\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/indusvalleytimes.com\/news\/#\/schema\/person\/229ac2ee13eea90327e2e7301c3ef206","name":"indadmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9b6f9b03321fc8effd1d678eb205a8c244bf8b1ceb3282aa64a44cda4666e3ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9b6f9b03321fc8effd1d678eb205a8c244bf8b1ceb3282aa64a44cda4666e3ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9b6f9b03321fc8effd1d678eb205a8c244bf8b1ceb3282aa64a44cda4666e3ea?s=96&d=mm&r=g","caption":"indadmin"},"url":"https:\/\/indusvalleytimes.com\/news\/author\/indadmin\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/posts\/34152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/comments?post=34152"}],"version-history":[{"count":0,"href":"https:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/posts\/34152\/revisions"}],"wp:attachment":[{"href":"https:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/media?parent=34152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/categories?post=34152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/indusvalleytimes.com\/news\/wp-json\/wp\/v2\/tags?post=34152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}